{"id":12518,"date":"2013-03-18T00:58:33","date_gmt":"2013-03-17T23:58:33","guid":{"rendered":"http:\/\/rusoch.fr\/?p=12518"},"modified":"2015-03-17T21:18:03","modified_gmt":"2015-03-17T20:18:03","slug":"luvr-a-la-russe-louvre-a-la-russe","status":"publish","type":"post","link":"https:\/\/rusoch.fr\/fr\/events\/luvr-a-la-russe-louvre-a-la-russe.html","title":{"rendered":" Louvre \u00e0 la russe\u2009?"},"content":{"rendered":"<p><span class=\"hidden_text\">\u0412 \u043d\u0430\u0447\u0430\u043b\u0435 \u0444\u0435\u0432\u0440\u0430\u043b\u044f <em>\u0424\u0440\u0430\u043d\u043a\u043e-\u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0430\u044f \u0442\u043e\u0440\u0433\u043e\u0432\u043e-\u043f\u0440\u043e\u043c\u044b\u0448\u043b\u0435\u043d\u043d\u0430\u044f \u043f\u0430\u043b\u0430\u0442\u0430 <\/em>(CCIFR) \u043f\u043e\u0434\u043f\u0438\u0441\u0430\u043b\u0430 \u0434\u043e\u0433\u043e\u0432\u043e\u0440 \u0441 \u041b\u0443\u0432\u0440\u043e\u043c, \u043f\u0440\u0435\u0434\u0443\u0441\u043c\u0430\u0442\u0440\u0438\u0432\u0430\u044e\u0449\u0438\u0439 \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u043a\u0443 \u0440\u0430\u0437\u0432\u0438\u0442\u0438\u044f \u044d\u043a\u0441\u043f\u043e\u0437\u0438\u0446\u0438\u0438 \u0440\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430. \u041f\u043e\u0442\u0440\u044f\u0441\u0435\u043d\u043d\u044b\u0439 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u043e\u0439 <em>\u00ab\u0421\u0432\u044f\u0442\u0430\u044f \u0420\u0443\u0441\u044c\u00bb<\/em>, \u043f\u0440\u043e\u0448\u0435\u0434\u0448\u0435\u0439 \u0432 \u044d\u0442\u043e\u043c \u043c\u0443\u0437\u0435\u0435 \u0432 2010 \u0433\u043e\u0434\u0443, \u0434\u0438\u0440\u0435\u043a\u0442\u043e\u0440 <em>\u041b\u0443\u0432\u0440\u0430 <\/em>\u0410\u043d\u0440\u0438 <em>\u041b\u0443\u0430\u0440\u0435\u0442\u0442<\/em> \u043e\u0445\u0430\u0440\u0430\u043a\u0442\u0435\u0440\u0438\u0437\u043e\u0432\u0430\u043b \u043e\u0442\u0441\u0443\u0442\u0441\u0442\u0432\u0438\u0435 \u0432 \u043d\u0435\u043c \u0440\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430 \u043a\u0430\u043a \u00ab\u043d\u0435\u0447\u0442\u043e \u0430\u0431\u0441\u043e\u043b\u044e\u0442\u043d\u043e \u0448\u043e\u043a\u0438\u0440\u0443\u044e\u0449\u0435\u0435\u00bb.<\/span><\/p>\n<p><span lang=\"fr\">D\u00e9but f\u00e9vrier, <em>la Chambre<\/em><em> de commerce et d&#39;industrie franco-russe<\/em> (CCIFR) a sign\u00e9 un accord avec le Louvre qui pr\u00e9voit de soutenir le d\u00e9veloppement d&#39;exposition d&#39;art russe. Bouscul\u00e9 depuis l&#39;exposition <em>\u00ab\u00a0Sainte Russie\u00a0\u00bb<\/em> organis\u00e9e au sein du mus\u00e9e en 2010, le directeur du Mus\u00e9e, <em>Henri Loyrette<\/em> a caract\u00e9ris\u00e9 l&#39;absence <em>d&#39;art russe <\/em>dans le mus\u00e9e comme \u00e9tant \u00ab\u00a0absolument choquant\u00a0\u00bb.<\/span><\/p>\n<p><!--more--><\/p>\n<p><div style=\"width: 610px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/files\/2013\/03\/c2a9-paris-tourist-office-photographe-jacques-lebar-cte-ieoh-ming-pei.jpg\"><img loading=\"lazy\" class=\"shutterset\" alt=\"c2a9-paris-tourist-office-photographe-jacques-lebar-cte-ieoh-ming-pei\" src=\"http:\/\/rusoch.fr\/files\/2013\/03\/c2a9-paris-tourist-office-photographe-jacques-lebar-cte-ieoh-ming-pei-600x380.jpg\" width=\"600\" height=\"380\" \/><\/a><p class=\"wp-caption-text\">\u041f\u0438\u0440\u0430\u043c\u0438\u0434\u0430 \u041b\u0443\u0432\u0440\u0430 | Pyramide du Louvre \u00a9Paris Tourist Office, Photographe Jacques Lebar<\/p><\/div><\/p>\n<p><span class=\"hidden_text\">\u041c\u043d\u0435 \u043a\u0430\u0436\u0435\u0442\u0441\u044f, \u0447\u0442\u043e \u043c\u0435\u0441\u044c\u0435 <em>\u041b\u0443\u0430\u0440\u0435\u0442\u0442<\/em> \u043f\u043e\u0434\u043e\u0431\u0440\u0430\u043b \u0443\u0436 \u0441\u043b\u0438\u0448\u043a\u043e\u043c \u0441\u0438\u043b\u044c\u043d\u043e\u0435 \u0441\u043b\u043e\u0432\u043e, \u0447\u0442\u043e\u0431\u044b \u043e\u0445\u0430\u0440\u0430\u043a\u0442\u0435\u0440\u0438\u0437\u043e\u0432\u0430\u0442\u044c \u043d\u0435\u0434\u043e\u0441\u0442\u0430\u0442\u043e\u0447\u043d\u043e\u0435 \u0437\u043d\u0430\u043a\u043e\u043c\u0441\u0442\u0432\u043e \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u0441\u043a\u043e\u0439, \u0434\u0430 \u0438 \u043c\u0438\u0440\u043e\u0432\u043e\u0439 \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u043d\u043e\u0439 \u043e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0441\u0442\u0438 \u0441 \u0440\u0443\u0441\u0441\u043a\u0438\u043c \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u043e\u043c. \u0418\u0431\u043e <strong><em>\u043d\u0435 \u043e\u0434\u0438\u043d \u0442\u043e\u043b\u044c\u043a\u043e \u041b\u0443\u0432\u0440 \u043d\u0435 \u0440\u0430\u0441\u043f\u043e\u043b\u0430\u0433\u0430\u0435\u0442 \u0434\u043e\u0441\u0442\u043e\u0439\u043d\u044b\u043c \u0441\u043e\u0431\u0440\u0430\u043d\u0438\u0435\u043c \u0440\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430<\/em><\/strong> (\u043d\u0435\u0441\u043a\u043e\u043b\u044c\u043a\u043e \u0438\u043a\u043e\u043d \u0438 \u0436\u0438\u0432\u043e\u043f\u0438\u0441\u043d\u044b\u0445 \u043f\u043e\u043b\u043e\u0442\u0435\u043d \u043d\u0435 \u0432 \u0441\u0447\u0435\u0442). \u0417\u0430 \u043f\u0440\u0435\u0434\u0435\u043b\u0430\u043c\u0438 \u0420\u043e\u0441\u0441\u0438\u0438 \u0432\u043e\u043e\u0431\u0449\u0435, \u043f\u043e\u0436\u0430\u043b\u0443\u0439, \u0442\u0440\u0443\u0434\u043d\u043e \u043d\u0430\u0439\u0442\u0438 \u0431\u043e\u043b\u0435\u0435 \u0438\u043b\u0438 \u043c\u0435\u043d\u0435\u0435 \u0441\u0435\u0440\u044c\u0435\u0437\u043d\u043e\u0435 \u043f\u043e\u0434\u043e\u0431\u043d\u043e\u0435 \u0441\u043e\u0431\u0440\u0430\u043d\u0438\u0435. \u0428\u043e\u043a\u0438\u0440\u0443\u044e\u0449\u0435\u0439 (\u0432 \u0445\u043e\u0440\u043e\u0448\u0435\u043c \u0441\u043c\u044b\u0441\u043b\u0435 \u044d\u0442\u043e\u0433\u043e \u0441\u043b\u043e\u0432\u0430) \u0431\u044b\u043b\u0430 \u0441\u043a\u043e\u0440\u0435\u0435 \u0441\u0430\u043c\u0430 \u043b\u0443\u0432\u0440\u0441\u043a\u0430\u044f \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0430, \u043a\u043e\u0442\u043e\u0440\u0430\u044f, \u043a\u0430\u0436\u0435\u0442\u0441\u044f, \u0432\u043e\u0431\u0440\u0430\u043b\u0430 \u0432 \u0441\u0435\u0431\u044f \u0447\u0443\u0442\u044c \u043b\u0438 \u043d\u0435 \u0432\u0441\u0435 \u043f\u0440\u0438\u0433\u043e\u0434\u043d\u044b\u0435 \u043a \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442\u0438\u0440\u043e\u0432\u043a\u0435 \u0436\u0435\u043c\u0447\u0443\u0436\u0438\u043d\u044b \u0434\u0440\u0435\u0432\u043d\u0435\u0440\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430. \u041f\u0440\u0438 \u0432\u0438\u0434\u0435 \u044d\u0442\u043e\u0433\u043e \u0432\u0435\u043b\u0438\u043a\u043e\u043b\u0435\u043f\u0438\u044f \u0442\u0440\u0443\u0434\u043d\u043e \u0431\u044b\u043b\u043e \u0443\u0434\u0435\u0440\u0436\u0430\u0442\u044c\u0441\u044f \u043e\u0442 \u043f\u043e\u0441\u044b\u043f\u0430\u043d\u0438\u044f \u0433\u043e\u043b\u043e\u0432\u044b \u043f\u0435\u043f\u043b\u043e\u043c. \u041c\u0430\u0441\u0448\u0442\u0430\u0431 \u0432\u043b\u0438\u044f\u043d\u0438\u044f \u044d\u0442\u043e\u0439 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0438 \u043d\u0430 \u0443\u043c\u044b \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u043e\u0432 \u043c\u043e\u0436\u043d\u043e \u0441\u0440\u0430\u0432\u043d\u0438\u0442\u044c \u043f\u043e\u0436\u0430\u043b\u0443\u0439 \u0447\u0442\u043e \u0441\u043e \u0437\u043d\u0430\u043c\u0435\u043d\u0438\u0442\u044b\u043c\u0438 \u00ab\u0414\u044f\u0433\u0438\u043b\u0435\u0432\u0441\u043a\u0438\u043c\u0438 \u0441\u0435\u0437\u043e\u043d\u0430\u043c\u0438\u00bb. \u041e \u043d\u0435\u0439 \u0434\u043e \u0441\u0438\u0445 \u043f\u043e\u0440 \u0432\u0441\u043f\u043e\u043c\u0438\u043d\u0430\u044e\u0442 \u0441 \u043f\u0440\u0438\u0434\u044b\u0445\u0430\u043d\u0438\u0435\u043c \u0438 \u043c\u0435\u0447\u0442\u0430\u0442\u0435\u043b\u044c\u043d\u043e \u0437\u0430\u043a\u0430\u0442\u044b\u0432\u0430\u044e\u0442 \u0433\u043b\u0430\u0437\u0430. \u0414\u0430\u0436\u0435 \u0440\u0430\u0431\u043e\u0442\u043d\u0438\u043a\u0438 \u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u0445 \u043c\u0443\u0437\u0435\u0435\u0432 \u043f\u043e \u0432\u043e\u0437\u043c\u043e\u0436\u043d\u043e\u0441\u0442\u0438 \u0441\u0442\u0430\u0440\u0430\u043b\u0438\u0441\u044c \u043f\u0440\u0438\u0435\u0445\u0430\u0442\u044c \u0438 \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043d\u0430 <strong>\u0445\u0440\u0435\u0441\u0442\u043e\u043c\u0430\u0442\u0438\u0439\u043d\u044b\u0435 \u043f\u0440\u043e\u0438\u0437\u0432\u0435\u0434\u0435\u043d\u0438\u044f, \u0432\u043f\u0435\u0440\u0432\u044b\u0435 \u0441\u043e\u0431\u0440\u0430\u043d\u043d\u044b\u0435 \u0432 \u043e\u0434\u043d\u043e\u043c \u043c\u0435\u0441\u0442\u0435<\/strong>.<\/span><\/p>\n<p><span class=\"hidden_text\">\u0423\u0441\u043f\u0435\u0445 <em>\u00ab\u0421\u0432\u044f\u0442\u043e\u0439 \u0420\u0443\u0441\u0438\u00bb<\/em> \u0441\u0432\u044f\u0437\u0430\u043d \u0441 \u0435\u0449\u0435 \u043e\u0434\u043d\u0438\u043c \u043d\u0435\u043c\u0430\u043b\u043e\u0432\u0430\u0436\u043d\u044b\u043c \u0444\u0430\u043a\u0442\u043e\u043c: \u0435\u0441\u043b\u0438 \u0448\u0438\u0440\u043e\u043a\u043e\u0439 \u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0447\u0442\u043e-\u0442\u043e \u0438 \u0438\u0437\u0432\u0435\u0441\u0442\u043d\u043e \u043e \u0440\u0443\u0441\u0441\u043a\u043e\u043c \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0435, \u0442\u0430\u043a \u044d\u0442\u043e \u0442\u0440\u0430\u0434\u0438\u0446\u0438\u043e\u043d\u043d\u0430\u044f \u0441\u0432\u044f\u0437\u043a\u0430 \u0438\u043a\u043e\u043d\u043e\u043f\u0438\u0441\u044c-\u0430\u0432\u0430\u043d\u0433\u0430\u0440\u0434. \u0420\u0430\u0441\u043f\u043e\u043b\u043e\u0436\u0438\u0432\u0448\u0438\u0435\u0441\u044f \u043c\u0435\u0436\u0434\u0443 \u043d\u0438\u043c\u0438 \u0434\u0432\u0430 \u0432\u0435\u043a\u0430 \u0440\u0443\u0441\u0441\u043a\u043e\u0439 \u0445\u0443\u0434\u043e\u0436\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0439 \u0436\u0438\u0437\u043d\u0438 \u0431\u0443\u0434\u0442\u043e \u043a\u0430\u043d\u0443\u043b\u0438 \u0432 \u043b\u0435\u0442\u0443. \u0427\u0430\u0441\u0442\u043e \u044d\u0442\u043e\u0442 \u043f\u0440\u043e\u0431\u0435\u043b \u0432 \u0437\u043d\u0430\u043d\u0438\u044f\u0445 \u043e\u0431\u044a\u044f\u0441\u043d\u044f\u044e\u0442 \u0432\u0442\u043e\u0440\u0438\u0447\u043d\u043e\u0441\u0442\u044c\u044e \u0440\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430 \u044d\u0442\u043e\u0433\u043e \u043f\u0435\u0440\u0438\u043e\u0434\u0430, \u0441\u043b\u0438\u0448\u043a\u043e\u043c \u0441\u0438\u043b\u044c\u043d\u044b\u043c \u0432\u043b\u0438\u044f\u043d\u0438\u0435\u043c \u0435\u0432\u0440\u043e\u043f\u0435\u0439\u0441\u043a\u0438\u0445 \u0445\u0443\u0434\u043e\u0436\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0445 \u0448\u043a\u043e\u043b. \u041d\u043e \u043c\u043e\u0436\u0435\u0442 \u0431\u044b\u0442\u044c \u0434\u0435\u043b\u043e \u043d\u0435 \u0441\u0442\u043e\u043b\u044c\u043a\u043e \u0432\u043e \u0432\u0442\u043e\u0440\u0438\u0447\u043d\u043e\u0441\u0442\u0438 \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430, \u0441\u043a\u043e\u043b\u044c\u043a\u043e \u043f\u043e\u043f\u0440\u043e\u0441\u0442\u0443 \u0432 \u043d\u0435\u0434\u043e\u0441\u0442\u0430\u0442\u043e\u0447\u043d\u043e\u0439 \u0438\u043d\u0444\u043e\u0440\u043c\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u043e\u0441\u0442\u0438 \u0448\u0438\u0440\u043e\u043a\u043e\u0439 \u043f\u0443\u0431\u043b\u0438\u043a\u0438?<\/span><\/p>\n<p><span class=\"hidden_text\">\u0421 \u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u043e\u0439 \u0441\u0442\u043e\u0440\u043e\u043d\u044b \u043d\u044b\u043d\u0435\u0448\u043d\u0435\u0435 \u0441\u043e\u0433\u043b\u0430\u0448\u0435\u043d\u0438\u0435 \u0441 <em>\u041b\u0443\u0432\u0440\u043e\u043c<\/em>&nbsp;&mdash; \u044d\u0442\u043e \u0438\u043c\u0435\u043d\u043d\u043e <strong>\u043f\u043e\u043f\u044b\u0442\u043a\u0430 \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u0438\u0437\u0430\u0446\u0438\u0438 \u0440\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430<\/strong>, \u0431\u043b\u0430\u0433\u043e\u0435 \u043d\u0430\u0447\u0438\u043d\u0430\u043d\u0438\u0435, \u043a\u043e\u0442\u043e\u0440\u043e\u0435 \u043d\u0435 \u043c\u043e\u0436\u0435\u0442 \u043d\u0435 \u0432\u044b\u0437\u044b\u0432\u0430\u0442\u044c \u0443\u0432\u0430\u0436\u0435\u043d\u0438\u044f. \u041f\u0440\u0430\u0432\u0434\u0430, \u0432 \u0441\u0442\u0440\u0435\u043c\u043b\u0435\u043d\u0438\u0438 \u0441\u043e\u0431\u0440\u0430\u0442\u044c \u0434\u043e\u0441\u0442\u043e\u0439\u043d\u0443\u044e \u043a\u043e\u043b\u043b\u0435\u043a\u0446\u0438\u044e \u0440\u0443\u0441\u0441\u043a\u043e\u0439 \u0436\u0438\u0432\u043e\u043f\u0438\u0441\u0438 (\u0438\u043c\u0435\u043d\u043d\u043e \u044d\u0442\u043e\u0442 \u0432\u0438\u0434 \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430 \u0432\u044b\u0437\u0432\u0430\u043b \u0443 \u043c\u0443\u0437\u0435\u0439\u0449\u0438\u043a\u043e\u0432 \u043d\u0430\u0438\u0431\u043e\u043b\u044c\u0448\u0438\u0439 \u0438\u043d\u0442\u0435\u0440\u0435\u0441) <em>\u041b\u0443\u0432\u0440<\/em> \u043e\u0433\u0440\u0430\u043d\u0438\u0447\u0435\u043d \u0432\u0440\u0435\u043c\u0435\u043d\u043d\u044b\u043c\u0438 \u0440\u0430\u043c\u043a\u0430\u043c\u0438: \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u043e \u043f\u043e\u0441\u043b\u0435 1850 \u0433\u043e\u0434\u0430 \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u0432\u043e\u0442\u0447\u0438\u043d\u043e\u0439 \u043c\u0443\u0437\u0435\u044f \u041e\u0440\u0441\u044d.<\/span><\/p>\n<p><span class=\"hidden_text\">\u0416\u0430\u0434\u043d\u044b\u0439 \u0434\u043e \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u043d\u043e\u0439 \u044d\u043a\u0441\u043f\u0430\u043d\u0441\u0438\u0438 \u0430\u0432\u0442\u043e\u0440 \u0442\u0443\u0442 \u0436\u0435 \u0432\u0441\u043f\u043e\u043c\u0438\u043d\u0430\u0435\u0442 \u0432\u0438\u0441\u044f\u0449\u0438\u0439 \u0442\u0430\u043c \u043f\u043e\u0440\u0442\u0440\u0435\u0442 \u043a\u0438\u0441\u0442\u0438 \u0421\u0435\u0440\u043e\u0432\u0430, \u0431\u0443\u043a\u0432\u0430\u043b\u044c\u043d\u043e \u043f\u0440\u0438\u043a\u043e\u0432\u044b\u0432\u0430\u044e\u0449\u0438\u0439 \u043a \u0441\u0435\u0431\u0435 \u0432\u0437\u0433\u043b\u044f\u0434 \u043f\u043e\u0441\u0435\u0442\u0438\u0442\u0435\u043b\u044f, \u0438 \u0442\u044f\u0436\u0435\u043b\u043e \u0432\u0437\u0434\u044b\u0445\u0430\u0435\u0442: \u0432\u043e\u0442 \u0431\u044b \u0438 \u0441 \u041e\u0440\u0441\u044d \u0437\u0430\u043a\u043b\u044e\u0447\u0438\u0442\u044c \u043c\u0430\u043b\u0435\u043d\u044c\u043a\u0438\u0439 \u0434\u043e\u0433\u043e\u0432\u043e\u0440 \u043e \u0441\u043e\u0442\u0440\u0443\u0434\u043d\u0438\u0447\u0435\u0441\u0442\u0432\u0435, \u0432\u0435\u0434\u044c \u0438 \u043f\u043e\u0441\u043b\u0435 1850 \u0433\u043e\u0434\u0430 \u0432 \u0440\u0443\u0441\u0441\u043a\u043e\u043c \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0435 \u0435\u0441\u0442\u044c \u043d\u0430 \u0447\u0442\u043e \u0432\u0437\u0433\u043b\u044f\u043d\u0443\u0442\u044c. \u041a\u0440\u043e\u043c\u0435 \u0442\u043e\u0433\u043e, \u0434\u0438\u0440\u0435\u043a\u0442\u043e\u0440 <em>\u0424\u0440\u0430\u043d\u043a\u043e-\u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u043e\u0439 \u0442\u043e\u0440\u0433\u043e\u0432\u043e-\u043f\u0440\u043e\u043c\u044b\u0448\u043b\u0435\u043d\u043d\u043e\u0439 \u043f\u0430\u043b\u0430\u0442\u044b <\/em>\u041f\u0430\u0432\u0435\u043b \u0428\u0438\u043d\u0441\u043a\u0438\u0439 \u0432 \u043e\u0434\u043d\u043e\u043c \u0438\u0437 \u0438\u043d\u0442\u0435\u0440\u0432\u044c\u044e \u0443\u0442\u043e\u0447\u043d\u0438\u043b, \u0447\u0442\u043e <em>\u041b\u0443\u0432\u0440 <\/em>\u043d\u0430\u0446\u0435\u043b\u0435\u043d \u043d\u0430 \u0441\u043e\u0431\u0438\u0440\u0430\u043d\u0438\u0435 \u0440\u0443\u0441\u0441\u043a\u043e\u0439 \u0436\u0438\u0432\u043e\u043f\u0438\u0441\u0438 \u0432 \u043e\u0441\u043d\u043e\u0432\u043d\u043e\u043c \u043f\u0435\u0440\u0432\u043e\u0439 \u0442\u0440\u0435\u0442\u0438 XIX \u0432\u0435\u043a\u0430. \u0418\u043d\u0442\u0435\u0440\u0435\u0441 \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u043e\u0432 \u043a \u044d\u0442\u043e\u043c\u0443 \u043f\u0435\u0440\u0438\u043e\u0434\u0443 \u043b\u0435\u0433\u043a\u043e \u043e\u0431\u044a\u044f\u0441\u043d\u0438\u043c: \u044d\u0442\u043e \u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u0432\u0440\u0435\u043c\u044f \u043c\u043e\u0434\u044b \u043d\u0430 \u0432\u0441\u0435 \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u0441\u043a\u043e\u0435, \u043d\u043e \u0438 \u043f\u0435\u0440\u0438\u043e\u0434 \u043d\u0430\u043f\u043e\u043b\u0435\u043e\u043d\u043e\u0432\u0441\u043a\u0438\u0445 \u0432\u043e\u0439\u043d, \u043c\u043e\u043c\u0435\u043d\u0442, \u043a\u043e\u0433\u0434\u0430 \u0440\u0443\u0441\u0441\u043a\u0430\u044f \u0438 \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u0441\u043a\u0430\u044f \u0438\u0441\u0442\u043e\u0440\u0438\u044f \u043f\u0435\u0440\u0435\u0441\u0435\u043a\u043b\u0438\u0441\u044c \u043d\u0430 \u0441\u0442\u0430\u0440\u043e\u0439 \u0421\u043c\u043e\u043b\u0435\u043d\u0441\u043a\u043e\u0439 \u0434\u043e\u0440\u043e\u0433\u0435.<\/span><\/p>\n<p><span class=\"hidden_text\">\u0422\u0435\u043c \u043d\u0435 \u043c\u0435\u043d\u0435\u0435, \u0432\u0441\u0435 \u0436\u0435 <strong>\u043d\u0435\u0442 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0430 \u043e \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0438 \u043d\u043e\u0432\u043e\u0433\u043e \u043e\u0442\u0434\u0435\u043b\u0430<\/strong>, \u043f\u043e\u0441\u0432\u044f\u0449\u0435\u043d\u043d\u043e\u0433\u043e \u0438\u0441\u043a\u043b\u044e\u0447\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0440\u0443\u0441\u0441\u043a\u043e\u0439 \u0436\u0438\u0432\u043e\u043f\u0438\u0441\u0438 \u043f\u043e\u0441\u043b\u0435\u043f\u0435\u0442\u0440\u043e\u0432\u0441\u043a\u043e\u0433\u043e \u043f\u0435\u0440\u0438\u043e\u0434\u0430. \u0411\u0435\u0441\u0441\u0440\u043e\u0447\u043d\u043e\u0435 \u0441\u043e\u0433\u043b\u0430\u0448\u0435\u043d\u0438\u0435, \u043f\u043e\u0434\u043f\u0438\u0441\u0430\u043d\u043d\u043e\u0435 \u043c\u0435\u0436\u0434\u0443 <em>\u041b\u0443\u0432\u0440\u043e\u043c<\/em> \u0438 CCIFR, \u043f\u0440\u0435\u0434\u043f\u043e\u043b\u0430\u0433\u0430\u0435\u0442 \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0430\u0446\u0438\u044e \u0444\u043e\u043d\u0434\u0430, \u0441\u043f\u043e\u0441\u043e\u0431\u0441\u0442\u0432\u0443\u044e\u0449\u0435\u0433\u043e \u0441\u043e\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0438\u044e \u0438 \u0440\u0430\u0437\u0432\u0438\u0442\u0438\u044e \u043a\u043e\u043b\u043b\u0435\u043a\u0446\u0438\u0438 \u0440\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430 \u0432 \u043c\u0443\u0437\u0435\u0435. \u042d\u0442\u043e\u0442 \u0436\u0435 \u0444\u043e\u043d\u0434 \u0441\u0442\u0430\u043d\u0435\u0442 \u0441\u0432\u043e\u0435\u0433\u043e \u0440\u043e\u0434\u0430 \u043e\u0442\u043a\u0440\u044b\u0442\u043e\u0439 \u043c\u0443\u0437\u0435\u0439\u043d\u043e\u0439 \u043f\u043b\u043e\u0449\u0430\u0434\u043a\u043e\u0439, \u0433\u0434\u0435, \u043f\u043e \u043c\u0435\u0440\u0435 \u043f\u043e\u043f\u043e\u043b\u043d\u0435\u043d\u0438\u044f \u043a\u043e\u043b\u043b\u0435\u043a\u0446\u0438\u0438, \u0431\u0443\u0434\u0443\u0442 \u043f\u0440\u043e\u0445\u043e\u0434\u0438\u0442\u044c \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u0438, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0437\u0430\u0442\u0435\u043c \u043f\u043e\u043a\u0430\u0436\u0443\u0442 \u0438 \u0432 \u0420\u043e\u0441\u0441\u0438\u0438. \u0421\u0443\u0434\u044f \u043f\u043e \u043e\u043f\u044b\u0442\u0443 \u00ab<em>\u0421\u0432\u044f\u0442\u043e\u0439 \u0420\u0443\u0441\u0438\u00bb<\/em>, \u043f\u043e\u0438\u0441\u043a\u043e\u043c \u043f\u0440\u043e\u0438\u0437\u0432\u0435\u0434\u0435\u043d\u0438\u0439 \u0434\u043b\u044f <em>\u041b\u0443\u0432\u0440\u0430 <\/em>\u0431\u0443\u0434\u0443\u0442 \u0437\u0430\u043d\u0438\u043c\u0430\u0442\u044c\u0441\u044f \u0438\u0441\u043a\u043b\u044e\u0447\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u0441\u043a\u0438\u0435 \u0441\u043f\u0435\u0446\u0438\u0430\u043b\u0438\u0441\u0442\u044b, \u043d\u043e \u043e\u0431\u044a\u0435\u043c \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0433\u043e \u0438\u043c \u0444\u0438\u043d\u0430\u043d\u0441\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f \u043d\u0435 \u0440\u0430\u0437\u0433\u043b\u0430\u0448\u0430\u0435\u0442\u0441\u044f.<\/span><\/p>\n<p><span lang=\"fr\">Il me semble que <em>M Loyrette <\/em>a choisi un mot bien fort pour caract\u00e9riser le manque de connaissance de la communaut\u00e9 culturelle fran\u00e7aise, et m\u00eame mondiale pour <em>l&#39;art russe<\/em>. Car <strong>le<em> Louvre <\/em>n&#39;est pas le seul \u00e0 ne pas disposer d&#39;une collection d&#39;<em>art russe<\/em> digne de ce nom<\/strong> (quelques ic\u00f4nes et toiles ne suffisent pas). Si l&#39;on quitte les fronti\u00e8res de la Russie, il devient en g\u00e9n\u00e9ral difficile de trouver une collection plus ou moins s\u00e9rieuse. Le terme \u00ab\u00a0choquant\u00a0\u00bb (dans le bon sens du mot) est \u00e0 mon sens plus apte \u00e0 qualifier l&#39;exposition du <em>Louvre<\/em> qui a rassembl\u00e9 en son sein une partie, si pas l&#39;enti\u00e8ret\u00e9, des \u0153uvres d&#39;art ancien transportables. \u00c0 la vue de tant de magnificence, il aurait \u00e9t\u00e9 difficile de ne pas s&#39;\u00e9mouvoir. Pour donner une id\u00e9e de l&#39;impact de cette exposition, on peut la comparer aux c\u00e9l\u00e8bres \u00ab\u00a0saisons de Diaghilev\u00a0\u00bb. Leur souvenir reste vivace et provoque encore des regards r\u00eaveurs. M\u00eame les curateurs des mus\u00e9es russes ont essay\u00e9 selon leurs possibilit\u00e9s de venir admirer de leurs yeux toutes ces \u0153uvres r\u00e9unies en un seul lieu.<\/span><\/p>\n<p><span lang=\"fr\">Le succ\u00e8s de <em>\u00ab\u00a0Sainte Russie <\/em>\u00bb est \u00e9galement d\u00fb au fait assez important que s&#39;il y a bien quelque chose qui est connu du grand public de <em>l&#39;art russe<\/em>, ce sont les traditionnelles ic\u00f4nes et l&#39;avant-garde. Les deux si\u00e8cles entre ces p\u00e9riodes de la vie russe sont comme tomb\u00e9s dans l&#39;oubli. Souvent, cette lacune est expliqu\u00e9e par le fait que l&#39;art de cette p\u00e9riode est secondaire, trop influenc\u00e9 par les \u00e9coles europ\u00e9ennes. Mais peut-\u00eatre cette impression d&#39;art secondaire est-elle caus\u00e9e par un manque d&#39;information donn\u00e9e au grand public\u2009?<\/span><\/p>\n<p><span lang=\"fr\">En Russie,<strong> l&#39;accord actuel avec le <em>Louvre<\/em><\/strong><em> <\/em>est vu comme une tentative de promouvoir <em>l&#39;art russe<\/em>, une initiative louable qui ne peut que commander le respect. Toutefois, dans sa volont\u00e9 d&#39;assembler une collection digne de ce nom de peintures russes (le genre d&#39;\u0153uvre d&#39;art qui provoque le plus haut int\u00e9r\u00eat chez les curateurs de mus\u00e9es), le <em>Louvre<\/em> est limit\u00e9 dans le temps\u2009; et toutes les \u0153uvres d&#39;apr\u00e8s 1850 sont du domaine du mus\u00e9e d&#39;Orsay. L&#39;auteur, avide de connaissances, se rappelle ici le portrait issu du pinceau de Serov, qui attire litt\u00e9ralement l&#39;\u0153il du visiteur, et soupire p\u00e9niblement. En effet un petit pacte de coop\u00e9ration a \u00e9t\u00e9 conclu avec le Mus\u00e9e d&#39;Orsay\u2009; et pourtant<strong> il y a bien des choses dans l&#39;art russe apr\u00e8s 1850<\/strong>. De plus, le directeur de la <em>Chambre<\/em><em> de commerce et d&#39;industrie franco-russe <\/em>(CCIFR) Pavel Chinsky a pr\u00e9cis\u00e9 dans une de ses interviews que le <em>Louvre <\/em>tentait de rassembler une collection de peintures russes datant essentiellement du premier tiers du XIXe si\u00e8cle. L&#39;int\u00e9r\u00eat des Fran\u00e7ais pour cette p\u00e9riode s&#39;explique facilement. Cette p\u00e9riode ne marque pas seulement l&#39;\u00e9poque de la mode fran\u00e7aise, mais \u00e9galement celle des guerres napol\u00e9oniennes, lorsque l&#39;Histoire russe et fran\u00e7aise se sont crois\u00e9es sur le vieux chemin de Smolensk.<\/span><\/p>\n<p><span lang=\"fr\">N\u00e9anmoins, il n&#39;y a toujours pas d&#39;accord pour la cr\u00e9ation d&#39;un nouveau service consacr\u00e9 uniquement \u00e0 la peinture russe de la p\u00e9riode qui a suivi Pierre le Grand. L&#39;accord permanent sign\u00e9 entre le <em>Louvre<\/em> et CCIFR suppose l&#39;organisation d&#39;un fonds contribuant \u00e0 la cr\u00e9ation et au d\u00e9veloppement de la future collection d&#39;art russe du Mus\u00e9e. Ce m\u00eame fonds servira comme une sorte de mus\u00e9e ouvert o\u00f9 seront pr\u00e9sent\u00e9es les \u0153uvres au fur et \u00e0 mesure de leur acquisition ainsi que des expositions russes. \u00c0 en juger par l&#39;exposition \u00ab<em> Sainte Russie <\/em>\u00bb, les recherches d&#39;\u0153uvres seront confi\u00e9es uniquement \u00e0 des sp\u00e9cialistes fran\u00e7ais du <em>Louvre<\/em>, mais le budget du fond n&#39;a pas encore \u00e9t\u00e9 divulgu\u00e9.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9but f\u00e9vrier, la Chambre de commerce et d&#39;industrie franco-russe (CCIFR) a sign\u00e9 un accord avec le Louvre qui pr\u00e9voit de\u2026<\/p>\n","protected":false},"author":2,"featured_media":12520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[1596,1590,1592,1591,1594,30,480,1595],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts\/12518"}],"collection":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/comments?post=12518"}],"version-history":[{"count":0,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts\/12518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/media\/12520"}],"wp:attachment":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/media?parent=12518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/categories?post=12518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/tags?post=12518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}