{"id":209210,"date":"2017-03-20T00:27:16","date_gmt":"2017-03-19T23:27:16","guid":{"rendered":"http:\/\/rusoch.fr\/?p=209210"},"modified":"2017-06-23T22:31:25","modified_gmt":"2017-06-23T21:31:25","slug":"olland-vernul-turistov-vo-franciyu","status":"publish","type":"post","link":"https:\/\/rusoch.fr\/fr\/tour\/olland-vernul-turistov-vo-franciyu.html","title":{"rendered":"Fran\u00e7ois Hollande a fait revenir les touristes en France"},"content":{"rendered":"<p>Fran\u00e7ois Hollande, le pr\u00e9sident le plus impopulaire de l&#39;Histoire de France, est attaqu\u00e9 m\u00eame par son propre camp. Anne Hidalgo, le maire de Paris, et membre du m\u00eame parti que le pr\u00e9sident fran\u00e7ais, l&#39;a qualifi\u00e9 de &laquo;responsable de l\u2019immense g\u00e2chis du quinquennat qui se termine&raquo;.<!--more--><\/p>\n<p><div id=\"attachment_209212\" style=\"width: 546px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/files\/2017\/03\/11406915_10207323582234221_7960662756200532739_n.jpg\" rel=\"attachment wp-att-209212\"><img aria-describedby=\"caption-attachment-209212\" loading=\"lazy\" class=\"wp-image-209212 size-medium\" src=\"http:\/\/rusoch.fr\/files\/2017\/03\/11406915_10207323582234221_7960662756200532739_n-536x379.jpg\" alt=\"\" width=\"536\" height=\"379\" srcset=\"https:\/\/rusoch.fr\/files\/2017\/03\/11406915_10207323582234221_7960662756200532739_n-536x379.jpg 536w, https:\/\/rusoch.fr\/files\/2017\/03\/11406915_10207323582234221_7960662756200532739_n-768x543.jpg 768w, https:\/\/rusoch.fr\/files\/2017\/03\/11406915_10207323582234221_7960662756200532739_n-566x400.jpg 566w, https:\/\/rusoch.fr\/files\/2017\/03\/11406915_10207323582234221_7960662756200532739_n-600x424.jpg 600w, https:\/\/rusoch.fr\/files\/2017\/03\/11406915_10207323582234221_7960662756200532739_n.jpg 900w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><p id=\"caption-attachment-209212\" class=\"wp-caption-text\">Cr\u00e9dit: Vladimir Bazan<\/p><\/div><\/p>\n<p>Mais, enfin, une bonne nouvelle est arriv\u00e9e dans le paysage \u00e9conomique pour le pr\u00e9sident fran\u00e7ais : les touristes sont de retour en France.<\/p>\n<p><strong>Avez-vous un plan, Monsieur Fix ?<br \/>\n<\/strong><br \/>\nEn arrivant au pouvoir, les socialistes se sont accroch\u00e9s \u00e0 l&#39;industrie du tourisme du pays, pensant qu&#39;elle \u00e9tait la clef du retour de la croissance, avec plus de deux millions d&#39;emplois, impossibles \u00e0 d\u00e9localiser.<br \/>\n<strong>Laurent Fabius<\/strong>, alors ministre des Affaires \u00c9trang\u00e8res, consid\u00e9rait que le tourisme \u00e9tait le secteur \u00e9conomique principal du futur. Et la France, avec ses richesses in\u00e9puisables qui attirent les touristes \u00e9trangers, ne pouvait pas prendre de retard face aux autres pays.<br \/>\nCombien d&#39;autres pays peuvent proposer, au choix, des stations de ski, de remarquables stations baln\u00e9aires au bord de la mer ou de l&#39;oc\u00e9an, des villes pass\u00e9es dans la l\u00e9gende au cours des si\u00e8cles, et par-dessus tout, une cuisine c\u00e9l\u00e8bre et des vins, cognacs et champagnes connus dans le monde entier.<\/p>\n<p>La France pourrait facilement \u00eatre la premi\u00e8re destination touristique dans le monde, et elle pourrait tranquillement se reposer sur ses lauriers a affirm\u00e9 Laurent Fabius.<\/p>\n<p>Le ministre s&#39;est fix\u00e9 un but : 100 millions de touristes \u00e9trangers par an en 2020<br \/>\n\"Le &laquo;Plan Tourisme&raquo; est n\u00e9 en 2014, et pour qu&#39;il puisse se r\u00e9aliser, Laurent Fabius lui a trouv\u00e9 un milliard d&#39;euros.<\/p>\n<p>Il se trouve qu&#39;il n&#39;existe pas en France d&#39;\u00e9tablissement prestigieux sp\u00e9cifique \u00e0 la formation d&#39;agents de tourisme, comme &laquo;l\u2019\u00c9cole H\u00f4teli\u00e8re&raquo; \u00e0 Lausanne en Suisse. Les Fran\u00e7ais doivent donc se former \u00e0 l&#39;\u00e9tranger, mais il pourrait arriver un jour o\u00f9 ils trouveraient du travail \u00e0 l&#39;\u00e9tranger et ne pas rentrer en France, voil\u00e0 pourquoi il est important de valoriser les \u00e9coles de commerce fran\u00e7aises.<\/p>\n<p>Ce qui navre les touristes, c&#39;est qu&#39;ils ne peuvent actuellement pas se rendre dans le centre de la capitale depuis l\u2019a\u00e9roport rapidement. Aussit\u00f4t dit, aussit\u00f4t fait, on a commenc\u00e9 \u00e0 construire une ligne rapide &laquo;a\u00e9roport Charles de Gaulle&nbsp;&mdash; Paris&raquo;. Dans l&#39;attente du train, pour amadouer les voyageurs, on a mis en place un prix fixe pour une course de taxi entre la ville et l&#39;a\u00e9roport.<\/p>\n<p>La crise \u00e9conomique contraint les touristes \u00e0 moins d\u00e9penser, ainsi, la tendance est \u00e0 venir en week-end dans la capitale fran\u00e7aise. Mais en France, le dimanche est traditionnellement un jour de repos. Probl\u00e8me compliqu\u00e9, mais en surmontant les fortes protestations des syndicats, les socialistes ont introduit la loi Macron, qui permet aux commerces d\u2019\u00eatre ouvert le dimanche, au grand bonheur des touristes.<\/p>\n<p>Le probl\u00e8me principal, c&#39;est de prot\u00e9ger les touristes confiants des voleurs et des escrocs qui les prennent pour cibles.<br \/>\nUne id\u00e9e, renforcer les patrouilles de police avec leurs homologues \u00e9trangers, notamment chinois. Les d\u00e9veloppeurs du \"Plan Tourisme \" ont compris l\u2019int\u00e9r\u00eat d&#39;attirer les touristes venant d&#39;Asie et d&#39;Afrique.<\/p>\n<p>Mais en arrivant en France, les touristes \u00e9trangers sont l\u00e9g\u00e8rement perdus : autour d&#39;autant de monuments, le Wi-fi gratuit est pratiquement inexistant, et ce manque n&#39;a pas \u00e9t\u00e9 combl\u00e9.<br \/>\nLaurent Fabius s&#39;est d\u00e9plac\u00e9 \u00e0 travers le globe, en donnant de son temps et de sa personne. Un jour, pour pouvoir rencontrer ses homologues et partenaires chinois, il a d\u00fb quitter la table des n\u00e9gociations \u00e0 Kiev, d\u00e9chir\u00e9 par les manifestations de Ma\u00efdan.<\/p>\n<p>Mais la s\u00e9rie d&#39;attentats, qui a fait 238 morts, \u00e0 travers le pays a fait obstacle au plan des socialistes. Les touristes \u00e9trangers, et en particulier les Japonais, ont brusquement chang\u00e9 leurs plans de voyage, et massivement annul\u00e9 leurs voyages en France.<\/p>\n<p><strong> 2016, l&#39;ann\u00e9e de l&#39;effort du gouvernement Valls<br \/>\n<\/strong><br \/>\nManuel Valls a pris le relais \u00e0 la mise en place d&#39;une France qui attire apr\u00e8s l&#39;\u00e9viction du gouvernement de Laurent Fabius. &laquo;Le tourisme est \u00e0 l&#39;origine de 7,5% de la richesse nationale et de deux millions d&#39;empois&raquo; a dit le premier ministre En dehors du plan \u00e9conomique, le tourisme joue un r\u00f4le important quant \u00e0 l&#39;image de la France, qui ainsi consolide l&#39;influence du pays dans le monde.<\/p>\n<p><strong>10 millions d&#39;euros<\/strong> ont \u00e9t\u00e9 investis dans le renforcement de la s\u00e9curit\u00e9 des installations touristiques, principalement dans les moyens de surveillance.<\/p>\n<p><strong>4 millions d&#39;euros<\/strong> sont all\u00e9s dans le Fonds d&#39;urgence au spectacle vivant pour renforcer la s\u00e9curit\u00e9 des festivals<\/p>\n<p><strong>5,7 millions d&#39;euros<\/strong> ont servi au payement des loisirs des cat\u00e9gories sociales les plus pauvres, permettant ainsi \u00e0 70 milles retrait\u00e9s d&#39;aller en bord de mer en 2016.<\/p>\n<p>En 2017, sont apparus les &laquo;ch\u00e8ques loisirs&raquo;, qui comme les &laquo;tickets restaurants&raquo; qui sont donn\u00e9s aux employ\u00e9s pour payer leurs repas, permettent aux personnes \u00e0 faible revenu de payer leurs vacances et de soutenir l&#39;industrie du tourisme.<\/p>\n<p>10,5 millions d&#39;euros ont permis de renforcer la sensibilisation des touristes fran\u00e7ais et \u00e9trangers.<br \/>\nEn d\u00e9pit des efforts d\u00e9ploy\u00e9s, Manuel Valls estime que les progr\u00e8s de la France ne sont pas encore suffisants. En effet, elle n&#39;est qu&#39;\u00e0 la troisi\u00e8me place dans le classement mondial en termes de revenus g\u00e9n\u00e9r\u00e9s par le tourisme, derri\u00e8re l&#39;Espagne et les \u00c9tats-Unis.<\/p>\n<p><strong>R\u00e9sultats de 2016<br \/>\n<\/strong><br \/>\nToutefois,<a href=\"http:\/\/rusoch.fr\/lang\/fr\/soc\/chempionat-evropy-po-futbolu-2016-nastroenie-ne-prazdnichnoe.html\"> le plus gros du travail a \u00e9t\u00e9 fait <\/a>et les r\u00e9sultats ne se sont pas fait attendre. Malgr\u00e9 les circonstances de l&#39;\u00e9tat d&#39;urgence face au risque \u00e9lev\u00e9 d&#39;attaques terroristes lors de l&#39;Euro de football 2016, cet \u00e9v\u00e9nement international grandiose a dur\u00e9 un mois et les stades fran\u00e7ais ont compt\u00e9 2,5 millions d&#39;entr\u00e9es, tout s&#39;est tr\u00e8s bien d\u00e9roul\u00e9, si on ne compte pas l&#39;incident avec les supporters russes.<\/p>\n<p><a href=\"http:\/\/rusoch.fr\/lang\/fr\/tour\/che-po-futbolu-franciya-sorvala-solidnyj-kush.html\">Avec cette comp\u00e9tition, la France a gagn\u00e9 1,2 milliard d&#39;euros.<\/a><\/p>\n<p>Et ce magnifique spectacle sportif a re\u00e7u une grande couverture m\u00e9diatique. \u00c0 travers leurs \u00e9crans de t\u00e9l\u00e9visions, des milliards de fans ont visit\u00e9 le pays, ce qui a, sans aucun doute, renforc\u00e9 la fiabilit\u00e9 de la France dans le monde. Si seulement quelques pourcents des t\u00e9l\u00e9spectateurs qui ont \u00e9t\u00e9 envo\u00fbt\u00e9 par la France apr\u00e8s avoir regard\u00e9 l&#39;Euro 2016, d\u00e9cide de la voir en vrai, c&#39;est des dizaines de millions de touristes suppl\u00e9mentaires, et pour atteindre le seuil des 100 millions, le pays a besoin de ces 15 ou 16 millions.<\/p>\n<p><strong>Les touristes asiatiques sont de retour en France<br \/>\n<\/strong><br \/>\nEn f\u00e9vrier 2017, il a \u00e9t\u00e9 s\u00fbr que les touristes asiatiques \u00e9taient de retour en France.<br \/>\nLes longtemps attendus touristes japonais sont retourn\u00e9s dans les rues de Paris, leur nombre a augment\u00e9 de 60 % par rapport \u00e0 la m\u00eame p\u00e9riode l&#39;ann\u00e9e derni\u00e8re, et \u00e7a a \u00e9t\u00e9 tout de suite remarqu\u00e9.<\/p>\n<p>Les Japonais sont un des clients pr\u00e9f\u00e9r\u00e9s de l&#39;industrie du tourisme, non seulement ils sont calmes et polis, mais 90 % se disent satisfaits de leur voyage, et c&#39;est pourquoi 30% d&#39;entre eux reviennent l&#39;ann\u00e9e d&#39;apr\u00e8s, ou au maximum dans les deux ans. Par cons\u00e9quent, parmi eux, se trouvent beaucoup de touristes confirm\u00e9s, qui savent tr\u00e8s bien ce qu&#39;ils veulent voir et faire. 90 % visitent les mus\u00e9es et les monuments, et seulement la moiti\u00e9 font du shopping. Ceux qui viennent pour la premi\u00e8re fois ont entre 45 et 55 % de chances de revenir.<\/p>\n<p>Un autre d\u00e9tail int\u00e9ressant, 55 % des Japonais passent par des agences de voyage, 30% r\u00e9servent sur internet et moins de 10% sur place. Plus de 80 % des touristes japonais logent simplement \u00e0 l\u2019h\u00f4tel. Le budget moyen d&#39;un Japonais pour son s\u00e9jour est de 1100 euros, ils restent en moyenne 5 jours, ce qui fait au total 400 millions d&#39;euros \u00e0 la France par an.<\/p>\n<p>Malheureusement, beaucoup de progr\u00e8s restent \u00e0 faire. Le nombre de touristes est seulement revenu au niveau auquel il \u00e9tait avant les attentats.<\/p>\n<p><strong>Sur le m\u00eame sujet<\/strong><\/p>\n<p><strong><a href=\"http:\/\/rusoch.fr\/lang\/fr\/guests\/nash-turist-v-parizhe-notre-touriste-russe-a-paris.html\">Les touristes fuient Paris \u00e0 cause des attentats de novembre<br \/>\nParis : une ville pour les touristes<br \/>\nNotre touriste russe \u00e0 Paris<br \/>\n<\/a><\/strong><strong><a href=\"http:\/\/rusoch.fr\/lang\/fr\/soc\/ne-uvidet-parizh-i-umeret-les-touristes-russes-boudent-la-france.html\">Les touristes russes boudent la France<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en Russe.<\/p>\n","protected":false},"author":2,"featured_media":209212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[1736,2052,1304,289],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts\/209210"}],"collection":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/comments?post=209210"}],"version-history":[{"count":0,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts\/209210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/media\/209212"}],"wp:attachment":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/media?parent=209210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/categories?post=209210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/tags?post=209210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}