{"id":217236,"date":"2019-09-15T10:52:33","date_gmt":"2019-09-15T09:52:33","guid":{"rendered":"http:\/\/rusoch.fr\/?p=217236"},"modified":"2019-09-23T19:07:49","modified_gmt":"2019-09-23T18:07:49","slug":"teatr-vahtangova-priedet-v-parizh","status":"publish","type":"post","link":"https:\/\/rusoch.fr\/fr\/events\/teatr-vahtangova-priedet-v-parizh.html","title":{"rendered":"Le th\u00e9\u00e2tre Vakhtangov en tourn\u00e9e \u00e0 Paris"},"content":{"rendered":"<p><strong>La c\u00e9l\u00e8bre Compagnie russe du Th\u00e9\u00e2tre Vakhtangov est de retour \u00e0 Paris \u00e0 l\u2019occasion de la tourn\u00e9e mondiale f\u00eatant son centi\u00e8me anniversaire.<\/strong><!--more--><\/p>\n<p><a href=\"http:\/\/rusoch.fr\/files\/2019\/09\/eugene-oneguine_4174459078261176403.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-217237\" src=\"http:\/\/rusoch.fr\/files\/2019\/09\/eugene-oneguine_4174459078261176403-259x379.jpg\" alt=\"\" width=\"259\" height=\"379\" srcset=\"https:\/\/rusoch.fr\/files\/2019\/09\/eugene-oneguine_4174459078261176403-259x379.jpg 259w, https:\/\/rusoch.fr\/files\/2019\/09\/eugene-oneguine_4174459078261176403-273x400.jpg 273w, https:\/\/rusoch.fr\/files\/2019\/09\/eugene-oneguine_4174459078261176403.jpg 600w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/><\/a><\/p>\n<p>Du 20 septembre au 3 octobre, 12 repr\u00e9sentations exceptionnelles de deux de leurs plus grandes productions\u00a0seront donn\u00e9es au Th\u00e9\u00e2tre Marigny : Eug\u00e8ne On\u00e9guine d\u2019Alexandre Pouchkine et Oncle Vania d\u2019Anton Tchekov.<\/p>\n<p>Les deux spectacles sont mis en sc\u00e8ne par <strong>Rimas Tuminas<\/strong>, le directeur artistique de la Compagnie. Ils seront donn\u00e9s en russe et surtitr\u00e9s en fran\u00e7ais.<br \/>\nLes repr\u00e9sentations ont \u00e9t\u00e9 mises en sc\u00e8ne par Rimas Tuminas avec ses fid\u00e8les co-auteurs\u00a0: le sc\u00e9nographe Adomas Yakovskis, le compositeur Faustas Latenas et la chor\u00e9graphe Ang\u00e9lica Kholina.<\/p>\n<p>Ces deux spectacles, couronn\u00e9s de plusieurs r\u00e9compenses prestigieuses, sont devenues les \u00ab\u00a0cartes de visite\u00a0\u00bb du Th\u00e9\u00e2tre Vakhtangov, qui se produit r\u00e9guli\u00e8rement en tourn\u00e9e \u00e0 travers le monde entier (Europe, \u00c9tats-Unis, Canada, Chine, Isra\u00ebl\u2026).<\/p>\n<p>Il n\u2019est finalement pas fr\u00e9quent de monter\u00a0<strong><em>Eug\u00e8ne On\u00e9guine<\/em><\/strong>\u00a0au th\u00e9\u00e2tre. On le pr\u00e9sente la plupart du temps dans ses versions op\u00e9ratique ou chor\u00e9graphique. Et m\u00eame si tout le monde conna\u00eet Pouchkine en Russie, peu sont capables de comprendre la port\u00e9e du po\u00e8te.<br \/>\nRimas Tuminas a choisi de ne mettre en sc\u00e8ne que la ligne principale de l\u2019\u0153uvre, \u00e0 savoir l\u2019amour que porte Tatiana \u00e0 On\u00e9guine.<br \/>\nAvec cette mise en sc\u00e8ne, il p\u00e9n\u00e8tre au c\u0153ur de l\u2019\u00e2me russe avec lyrisme et passion.<br \/>\nUn spectacle grandiose, salu\u00e9 par la presse internationale\u00a0: \u00ab\u00a0Cette production \u00e9patante de Rimas Tuminas est port\u00e9e par la parfaite combinaison entre les mots, la musique, le mime et le symbolisme\u00a0\u00bb (The Guardian).<\/p>\n<p>D\u00e9j\u00e0 pr\u00e9sent\u00e9 dans le monde entier (Russie, Grande-Bretagne, Espagne, Italie, Suisse, Etats-Unis et Canada), cette mise en sc\u00e8ne d\u2019<em><strong>Oncle Vania<\/strong> \u00a0<\/em>sera jou\u00e9e pour la premi\u00e8re fois \u00e0 Paris.<\/p>\n<p>Th\u00e9\u00e2tre, mime, musique\u2026 tous les arts sont r\u00e9unis autour d\u2019une vision propre \u00e0 Rimas Tuminas\u00a0qui s\u2019est rapproch\u00e9 le plus possible du texte de Tchekov. La trag\u00e9die et la farce sont ici \u00e9troitement li\u00e9es et on retrouve ce que Tchekov appelait \u00ab\u00a0com\u00e9die\u00a0\u00bb.<br \/>\nLa sc\u00e8ne est le champ de bataille des passions, des illusions perdues et des espoirs non concr\u00e9tis\u00e9s.<br \/>\nCette mise en sc\u00e8ne d\u2019Oncle Vania, dr\u00f4le et bouleversante \u00e0 la fois, est port\u00e9e par des com\u00e9diens exceptionnels.<\/p>\n<p>Le Th\u00e9\u00e2tre Vakhtangov, une des plus grandes institutions th\u00e9\u00e2trales mondiales, est consid\u00e9r\u00e9 comme La Com\u00e9die-Fran\u00e7aise russe.<\/p>\n<p>Des informations d\u00e9taill\u00e9es sont disponibles sur le site web du <a href=\"https:\/\/www.theatremarigny.fr\">Th\u00e9\u00e2tre Marigny<\/a>.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en Russe.<\/p>\n","protected":false},"author":2,"featured_media":217238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[1928,3223],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts\/217236"}],"collection":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/comments?post=217236"}],"version-history":[{"count":1,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts\/217236\/revisions"}],"predecessor-version":[{"id":217299,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/posts\/217236\/revisions\/217299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/media\/217238"}],"wp:attachment":[{"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/media?parent=217236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/categories?post=217236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rusoch.fr\/fr\/wp-json\/wp\/v2\/tags?post=217236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}