{"id":18008,"date":"2014-03-23T00:06:10","date_gmt":"2014-03-22T23:06:10","guid":{"rendered":"http:\/\/rusoch.fr\/?p=18008"},"modified":"2014-03-25T14:31:57","modified_gmt":"2014-03-25T13:31:57","slug":"34-j-parizhskij-knizhnyj-salon","status":"publish","type":"post","link":"https:\/\/rusoch.fr\/ru\/cult\/34-j-parizhskij-knizhnyj-salon.html","title":{"rendered":"34-\u0439 \u043f\u0430\u0440\u0438\u0436\u0441\u043a\u0438\u0439 \u041a\u043d\u0438\u0436\u043d\u044b\u0439 \u0441\u0430\u043b\u043e\u043d "},"content":{"rendered":"<p>20 \u043c\u0430\u0440\u0442\u0430 \u0441\u043e\u0441\u0442\u043e\u044f\u043b\u043e\u0441\u044c \u0442\u043e\u0440\u0436\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0435 \u043e\u0442\u043a\u0440\u044b\u0442\u0438\u0435 34-\u0433\u043e \u043f\u0430\u0440\u0438\u0436\u0441\u043a\u043e\u0433\u043e \u041a\u043d\u0438\u0436\u043d\u043e\u0433\u043e \u0441\u0430\u043b\u043e\u043d\u0430.<\/p>\n<p>\u0412 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u043c\u0435 \u0432\u0435\u0447\u0435\u0440\u0430: \u0432\u0441\u0442\u0443\u043f\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0435 \u0441\u043b\u043e\u0432\u043e \u043f\u0440\u0435\u043c\u044c\u0435\u0440-\u043c\u0438\u043d\u0438\u0441\u0442\u0440\u0430 \u0424\u0440\u0430\u043d\u0446\u0438\u0438 \u0416. -\u041c. \u042d\u0440\u043e, \u0440\u0435\u0447\u044c \u043f\u0440\u0435\u0437\u0438\u0434\u0435\u043d\u0442\u0430 \u0410\u0440\u0433\u0435\u043d\u0442\u0438\u043d\u044b \u041a\u0440\u0438\u0441\u0442\u0438\u043d\u044b \u041a\u0438\u0440\u0448\u043d\u0435\u0440 \u043d\u0430 \u0438\u0441\u043f\u0430\u043d\u0441\u043a\u043e\u043c \u0431\u0435\u0437 \u043f\u0435\u0440\u0435\u0432\u043e\u0434\u0430 \u0438 \u043f\u0438\u0441\u0430\u0442\u0435\u043b\u044c\u0441\u043a\u043e-\u0438\u0437\u0434\u0430\u0442\u0435\u043b\u044c\u0441\u043a\u0438\u0435 \u043c\u0435\u0436\u0434\u0443\u0441\u043e\u0431\u043e\u0439\u0447\u0438\u043a\u0438.<\/p>\n<div class=\"hidden_text\">L\u2019inauguration solennelle du 34<sup>\u00e8me<\/sup> Salon du Livre de Paris a eu lieu le 20 mars. Au programme de la soir\u00e9e\u00a0: le discours inaugural de Jean-Marc Ayrault (premier ministre fran\u00e7ais), un discours de la pr\u00e9sidente de l\u2019Argentine Cristina Kirchner (le pays est invit\u00e9 d\u2019honneur cette ann\u00e9e) en espagnol sans traduction, et des rencontres entre amis \u00e9crivains et \u00e9diteurs.<\/div>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_18015\" style=\"width: 610px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/cult\/34-j-parizhskij-knizhnyj-salon.html\/attachment\/foto-5\" rel=\"attachment wp-att-18015\"><img aria-describedby=\"caption-attachment-18015\" loading=\"lazy\" class=\"size-large wp-image-18015\" alt=\"\" src=\"http:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-5-600x388.jpg\" width=\"600\" height=\"388\" srcset=\"https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-5-600x388.jpg 600w, https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-5.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-18015\" class=\"wp-caption-text\">\u041a\u0440\u0438\u0441\u0442\u0438\u043d\u0430 \u041a\u0438\u0440\u0448\u043d\u0435\u0440 \u0438 \u0416\u0430\u043d-\u041c\u0430\u0440\u043a \u042d\u0440\u043e \u00a9Aliona Sovetova<\/p><\/div><\/p>\n<p>\u0421 \u043f\u044f\u0442\u043d\u0438\u0446\u044b, 21-\u0433\u043e \u043c\u0430\u0440\u0442\u0430, \u041a\u043d\u0438\u0436\u043d\u044b\u0439 \u0441\u0430\u043b\u043e\u043d \u043e\u0442\u043a\u0440\u044b\u043b \u0441\u0432\u043e\u0438 \u0434\u0432\u0435\u0440\u0438 \u0434\u043b\u044f \u0448\u0438\u0440\u043e\u043a\u043e\u0439 \u043f\u0443\u0431\u043b\u0438\u043a\u0438.<\/p>\n<p><b>\u041f\u043e\u0447\u0451\u0442\u043d\u044b\u0439 \u0433\u043e\u0441\u0442\u044c \u2013 \u0410\u0440\u0433\u0435\u043d\u0442\u0438\u043d\u0430<\/b>, \u043f\u0440\u0438\u0433\u043b\u0430\u0448\u0451\u043d\u043d\u0430\u044f \u0441\u0442\u043e\u043b\u0438\u0446\u0430 \u2013 \u0428\u0430\u043d\u0445\u0430\u0439. 1200 \u0438\u0437\u0434\u0430\u0442\u0435\u043b\u044c\u0441\u0442\u0432 \u043d\u0430 500 \u0441\u0442\u0435\u043d\u0434\u0430\u0445 \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u0438\u043b\u0438 \u0441\u0432\u043e\u0438 \u043a\u043d\u0438\u0433\u0438, \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u043a\u043e\u0442\u043e\u0440\u044b\u0445 \u0432\u044b\u0437\u044b\u0432\u0430\u0435\u0442 \u043d\u0435\u043b\u0435\u0433\u043a\u043e\u0435 \u0433\u043e\u043b\u043e\u0432\u043e\u043a\u0440\u0443\u0436\u0435\u043d\u0438\u0435, 4500 \u0430\u0432\u0442\u043e\u0440\u043e\u0432 \u0438\u0437 45 \u0441\u0442\u0440\u0430\u043d \u0438\u0445 \u043f\u043e\u0434\u043f\u0438\u0448\u0443\u0442. \u041e\u0442\u043a\u0440\u044b\u043b\u0438\u0441\u044c 5 \u0432\u044b\u0441\u0442\u0430\u0432\u043e\u043a, \u043f\u043e\u0441\u0432\u044f\u0449\u0451\u043d\u043d\u044b\u0445 \u0436\u0438\u0437\u043d\u0438 \u0438 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u043e\u043c\u0443 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044e \u0425\u0443\u043b\u0438\u043e \u041a\u043e\u0440\u0442\u0430\u0441\u0430\u0440\u0430 (L64), \u043a\u0438\u0442\u0430\u0439\u0441\u043a\u0438\u043c \u043a\u043e\u043c\u0438\u043a\u0441\u0430\u043c (O78), \u0442\u0432\u043e\u0440\u0447\u0435\u0441\u0442\u0432\u0443 \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u0441\u043a\u043e\u0433\u043e \u0445\u0443\u0434\u043e\u0436\u043d\u0438\u043a\u0430-\u043a\u0430\u0440\u0438\u043a\u0430\u0442\u0443\u0440\u0438\u0441\u0442\u0430 \u0421\u0435\u043c\u043f\u0435 (K98) \u0438 \u0441\u044e\u0436\u0435\u0442\u0443, \u043d\u0435 \u0442\u0435\u0440\u044f\u044e\u0449\u0435\u043c\u0443 \u0441\u0432\u0435\u0436\u0435\u0441\u0442\u0438 \u2013 \u0436\u0435\u043d\u0449\u0438\u043d\u0430\u043c \u0432 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u0435.<\/p>\n<div class=\"hidden_text\">Depuis vendredi, le 21 mars, le Salon du Livre a ouvert ses portes au grand public.<strong> L\u2019invit\u00e9 d\u2019honneur est l\u2019Argentine, et la capitale invit\u00e9e d\u2019honneur est Shanghai.<\/strong> 1200 maisons d\u2019\u00e9ditions et 500 stands ont pr\u00e9sent\u00e9 leurs livres, dont la qualit\u00e9 donne le vertige, 4500 auteurs venus de 45 pays diff\u00e9rents les d\u00e9dicaceront, il y a eu 5 expositions consacr\u00e9es \u00e0 la vie et \u00e0 l\u2019h\u00e9ritage litt\u00e9raire de Julio Cort\u00e1zar (L64), aux bandes dessin\u00e9es chinoises (O78), \u00e0 l\u2019\u0153uvre du peintre-caricaturiste fran\u00e7ais Semp\u00e9 (K98), et \u00e0 un sujet qui ne perd pas de sa fra\u00eecheur\u00a0: les femmes dans la litt\u00e9rature.<\/div>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_18020\" style=\"width: 543px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/cult\/34-j-parizhskij-knizhnyj-salon.html\/attachment\/foto-7\" rel=\"attachment wp-att-18020\"><img aria-describedby=\"caption-attachment-18020\" loading=\"lazy\" class=\"size-large wp-image-18020\" alt=\"\" src=\"http:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-7-533x400.jpg\" width=\"533\" height=\"400\" srcset=\"https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-7-533x400.jpg 533w, https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-7.jpg 1000w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a><p id=\"caption-attachment-18020\" class=\"wp-caption-text\">\u00a9Aliona Sovetova<\/p><\/div><\/p>\n<p>\u00a0\u00ab\u041b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u044b\u043c \u0436\u0435\u043d\u0449\u0438\u043d\u0430\u043c\u00bb \u0438 <b>\u00ab\u0436\u0435\u043d\u0449\u0438\u043d\u0430\u043c \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u044b\u00bb<\/b> \u0432 \u044d\u0442\u043e\u043c \u0433\u043e\u0434\u0443 \u0443\u0434\u0435\u043b\u044f\u0435\u0442\u0441\u044f \u0432\u043d\u0438\u043c\u0430\u043d\u0438\u0435 \u043e\u0441\u043e\u0431\u043e\u0435. \u041e\u0440\u0433\u0430\u043d\u0438\u0437\u0430\u0442\u043e\u0440\u044b \u0437\u0430\u0434\u0430\u044e\u0442\u0441\u044f \u0432\u043e\u043f\u0440\u043e\u0441\u043e\u043c \u043e \u0431\u0443\u0434\u0443\u0449\u0435\u043c \u0436\u0435\u043d\u0441\u043a\u043e\u0439 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u044b, \u043e \u0435\u0451 \u043c\u0435\u0441\u0442\u0435 \u0438 \u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0438, \u0438 \u0434\u0430\u0436\u0435, \u0432 \u043d\u0435\u043a\u043e\u0442\u043e\u0440\u043e\u043c \u0441\u043c\u044b\u0441\u043b\u0435, \u0441\u043f\u0430\u0441\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0439 \u0441\u0438\u043b\u0435. \u041f\u0438\u0441\u0430\u0442\u0435\u043b\u044c\u043d\u0438\u0446\u044b, \u0436\u0443\u0440\u043d\u0430\u043b\u0438\u0441\u0442\u043a\u0438, \u0438\u0437\u0434\u0430\u0442\u0435\u043b\u044c\u043d\u0438\u0446\u044b \u043f\u043e\u043f\u044b\u0442\u0430\u044e\u0442\u0441\u044f \u043d\u0430\u0439\u0442\u0438 \u043e\u0442\u0432\u0435\u0442\u044b \u043d\u0430 \u044d\u0442\u0438 \u0438 \u043c\u043d\u043e\u0433\u0438\u0435 \u0434\u0440\u0443\u0433\u0438\u0435 \u0430\u043a\u0442\u0443\u0430\u043b\u044c\u043d\u044b\u0435 \u0436\u0435\u043d\u0441\u043a\u0438\u0435 \u0432\u043e\u043f\u0440\u043e\u0441\u044b \u0432\u043e \u0432\u0440\u0435\u043c\u044f \u0437\u0430\u043f\u043b\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0445 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0438\u0439 \u0438 \u0434\u0435\u0431\u0430\u0442\u043e\u0432 (\u0441\u0442\u0435\u043d\u0434 U6 \u0438 C96).<\/p>\n<p>\u0412\u043d\u0438\u043c\u0430\u043d\u0438\u044e \u043f\u043e\u0441\u0435\u0442\u0438\u0442\u0435\u043b\u0435\u0439 \u043f\u0440\u0435\u0434\u043b\u043e\u0436\u0435\u043d\u044b \u0441\u0430\u043c\u044b\u0435 <b>\u043d\u0435\u0432\u0435\u0440\u043e\u044f\u0442\u043d\u044b\u0435 \u0430\u0442\u0435\u043b\u044c\u0435<\/b> \u2013 \u043e\u0442 \u0438\u0441\u043a\u0443\u0441\u0441\u0442\u0432\u0430 \u043a\u0443\u043b\u0438\u043d\u0430\u0440\u043d\u043e\u0433\u043e (S91) \u0434\u043e \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0438 \u0430\u0440\u0430\u0431\u0441\u043a\u043e\u0439 \u043a\u0430\u043b\u043b\u0438\u0433\u0440\u0430\u0444\u0438\u0438 (S46). \u0412 \u0440\u0430\u043c\u043a\u0430\u0445 \u043a\u043d\u0438\u0436\u043d\u043e\u0433\u043e \u0441\u0430\u043b\u043e\u043d\u0430 \u0437\u0430\u043f\u043b\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043e \u0432\u0440\u0443\u0447\u0435\u043d\u0438\u0435 11 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u044b\u0445 \u043f\u0440\u0435\u043c\u0438\u0439, \u0430 \u0442\u0430\u043a\u0436\u0435 \u0441\u043e\u0441\u0442\u043e\u044f\u0442\u0441\u044f \u043d\u0435\u0441\u043a\u043e\u043b\u044c\u043a\u043e \u0434\u0435\u0441\u044f\u0442\u043a\u043e\u0432 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446\u0438\u0439, \u043a\u0430\u043a \u0438\u043d\u043e\u0433\u0434\u0430 \u043a\u0430\u0436\u0435\u0442\u0441\u044f, \u043f\u043e \u0432\u0441\u0435\u043c \u0432\u043e\u043f\u0440\u043e\u0441\u0430\u043c \u0438 \u0441\u044e\u0436\u0435\u0442\u0430\u043c. \u0412 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u043f\u0440\u0438\u043c\u0435\u0440\u0430: \u00ab\u041c\u043e\u0436\u043d\u043e \u043b\u0438 \u043f\u0440\u043e\u0434\u0430\u0442\u044c \u0442\u0435\u043b\u043e?\u00bb, \u00ab\u041f\u043e\u0433\u043e\u0432\u043e\u0440\u0438\u043c \u043e \u0437\u0432\u0451\u0437\u0434\u0430\u0445?\u00bb, \u00ab\u041a\u0430\u043a \u043d\u0430\u043f\u0438\u0441\u0430\u0442\u044c \u043d\u0430\u0446\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u044b\u0439 \u0440\u0430\u0441\u0441\u043a\u0430\u0437?\u00bb, \u00ab\u0412\u0441\u0435 \u0441\u043e\u0448\u043b\u0438 \u0441 \u0443\u043c\u0430\u00bb, \u00ab\u0415\u0432\u0440\u0435\u0438 \u0438 \u043c\u0443\u0441\u0443\u043b\u044c\u043c\u0430\u043d\u0435, \u0441\u0432\u044f\u0437\u0430\u043d\u043d\u044b\u0435 \u0443\u0437\u0430\u043c\u0438 \u0438\u0441\u0442\u043e\u0440\u0438\u0438\u00bb, \u00ab\u041d\u0430\u0441\u043b\u0435\u0434\u0438\u0435 \u0432\u043e\u0441\u0442\u043e\u0447\u043d\u043e\u0439 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u044b \u043e\u043d-\u043b\u0430\u0439\u043d\u00bb, \u00ab\u042f\u043a\u0430\u0440\u0438 \u0432 40 \u043b\u0435\u0442\u00bb \u0438 \u0442.\u0434.<\/p>\n<div class=\"hidden_text\">Cette ann\u00e9e, on porte une attention particuli\u00e8re aux \u00ab\u00a0femmes litt\u00e9raires\u00a0\u00bb et aux \u00ab\u00a0femmes dans la litt\u00e9rature\u00a0\u00bb. Les organisateurs ont pos\u00e9 la question de l\u2019avenir de la litt\u00e9rature des femmes, de sa place et de sa signification, mais aussi dans un certain sens, de sa force salutaire. Les \u00e9crivaines, les journalistes, les \u00e9ditrices tentent de chercher des r\u00e9ponses \u00e0 ces nombreuses questions actuelles concernant les femmes, pendant des conf\u00e9rences planifi\u00e9es et des d\u00e9bats (stands U6 et C96).<\/div>\n<div class=\"hidden_text\">Les ateliers les plus invraisemblables sont propos\u00e9s \u00e0 l\u2019attention des visiteurs, de l\u2019art culinaire (S91) \u00e0 la pratique de la calligraphie arabe (S46). Dans le cadre du Salon du Livre, la remise de 11 prix litt\u00e9raires \u00e0 \u00e9t\u00e9 planifi\u00e9e, et se sont tenues quelques dizaines de conf\u00e9rences sur toutes les questions et sur tous les sujets. A titre d\u2019exemple\u00a0: \u00ab\u00a0Peut-on vendre le corps humain\u00a0?\u00a0\u00bb \u00ab\u00a0Et si on parlait des \u00e9toiles\u00a0?\u00a0\u00bb, \u00ab\u00a0Comment \u00e9crire un r\u00e9cit national\u00a0?\u00bb, \u00ab\u00a0Tous sont devenus fous\u00a0\u00bb, \u00ab\u00a0Juifs et Musulmans, mari\u00e9s par l\u2019histoire\u00a0\u00bb, \u00ab\u00a0L\u2019H\u00e9ritage de la litt\u00e9rature de l\u2019Est en ligne\u00a0\u00bb, \u00ab\u00a0Yakari a 40 ans\u00a0\u00bb etc.<\/div>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_18019\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/cult\/34-j-parizhskij-knizhnyj-salon.html\/attachment\/foto-1\" rel=\"attachment wp-att-18019\"><img aria-describedby=\"caption-attachment-18019\" loading=\"lazy\" class=\"size-large wp-image-18019\" alt=\"\" src=\"http:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-1-300x400.jpg\" width=\"300\" height=\"400\" srcset=\"https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-1-300x400.jpg 300w, https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-18019\" class=\"wp-caption-text\">Read Russia \u00a9Aliona Sovetova<\/p><\/div><\/p>\n<p>&nbsp;<\/p>\n<p>\u041d\u043e\u0432\u0430\u044f \u0442\u0435\u043c\u0430\u0442\u0438\u043a\u0430 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u044b\u0445 \u0432\u0441\u0442\u0440\u0435\u0447 \u044d\u0442\u043e\u0433\u043e \u0433\u043e\u0434\u0430 \u00ab\u0410 \u043a\u0430\u043a\u0430\u044f \u043a\u043d\u0438\u0433\u0430 \u0438\u0437\u043c\u0435\u043d\u0438\u043b\u0430 \u0432\u0430\u0448\u0443 \u0436\u0438\u0437\u043d\u044c?\u00bb (C96).\u00a0 \u041a\u0440\u0438\u0441\u0442\u0438\u0430\u043d \u0422\u043e\u0431\u0438\u0440\u0430, \u0414\u0443\u0433\u043b\u0430\u0441 \u041a\u0435\u043d\u043d\u0435\u0434\u0438, \u041f\u044c\u0435\u0440 \u0411\u0435\u0440\u0436\u0435, \u042d\u043b\u043e\u0438\u0437\u0430 \u0434\u2019\u041e\u0440\u043c\u0435\u0441\u0441\u043e\u043d \u0432\u0434\u043e\u0445\u043d\u043e\u0432\u044f\u0442 \u0441\u0432\u043e\u0438\u043c\u0438 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u044b\u043c\u0438 \u043e\u0442\u043a\u0440\u044b\u0442\u0438\u044f\u043c\u0438.<\/p>\n<p><b>\u0418\u0437 \u043d\u0435\u043e\u0436\u0438\u0434\u0430\u043d\u043d\u043e\u0433\u043e<\/b>: \u043d\u044b\u043d\u0435\u0448\u043d\u0438\u0439 \u043a\u043d\u0438\u0436\u043d\u044b\u0439 \u0441\u0430\u043b\u043e\u043d \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u0435\u0442 \u0441\u043e\u0432\u0435\u0440\u0448\u0438\u0442\u044c \u043f\u0440\u043e\u0433\u0443\u043b\u043a\u0443 \u043f\u043e \u041f\u0430\u0440\u0438\u0436\u0443 \u0432\u043c\u0435\u0441\u0442\u0435 \u0441 \u043f\u0438\u0441\u0430\u0442\u0435\u043b\u0435\u043c \u0414\u0443\u0433\u043b\u0430\u0441\u043e\u043c \u041a\u0435\u043d\u043d\u0435\u0434\u0438 \u043d\u0430 \u0430\u0432\u0442\u043e\u0431\u0443\u0441\u0435 30-\u044b\u0445 \u0433\u043e\u0434\u043e\u0432. \u0410 \u0424\u041d\u0410\u041a (\u043c\u0430\u0433\u0430\u0437\u0438\u043d \u0430\u0443\u0434\u0438\u043e \u0438 \u0432\u0438\u0434\u0435\u043e\u0442\u0435\u0445\u043d\u0438\u043a\u0438 \u2013 \u043f\u0440\u0438\u043c.\u0440\u0435\u0434.) \u043f\u0440\u0438\u0433\u043b\u0430\u0448\u0430\u0435\u0442 \u0441\u0434\u0435\u043b\u0430\u0442\u044c \u00ab\u0444\u043e\u0442\u043e \u043a\u043d\u0438\u0433\u043e\u0447\u0435\u044f\u00bb. \u0412\u0430\u0441 \u0437\u0430\u0432\u0435\u0434\u0443\u0442 \u0432 \u0447\u0451\u0440\u043d\u0443\u044e \u043a\u043b\u0430\u0434\u043e\u0432\u043a\u0443 \u0438 \u0441\u0444\u043e\u0442\u043e\u0433\u0440\u0430\u0444\u0438\u0440\u0443\u044e\u0442 \u0441\u043e \u0432\u0441\u043f\u044b\u0448\u043a\u043e\u0439, \u0432\u044b \u043d\u0438\u0447\u0435\u0433\u043e \u043d\u0435 \u0443\u0441\u043f\u0435\u0435\u0442\u0435 \u043f\u043e\u043d\u044f\u0442\u044c, \u043d\u043e \u043f\u043e\u0442\u043e\u043c \u043d\u0430 \u043e\u0442\u043f\u0435\u0447\u0430\u0442\u0430\u043d\u043d\u043e\u0439 \u0444\u043e\u0442\u043e\u0433\u0440\u0430\u0444\u0438\u0438 \u043e\u0431\u043d\u0430\u0440\u0443\u0436\u0438\u0442\u0435, \u0447\u0442\u043e \u0432\u044b \u0431\u044b\u043b\u0438 \u043d\u0435 \u0432 \u043a\u043b\u0430\u0434\u043e\u0432\u043a\u0435 \u0432\u043e\u0432\u0441\u0435, \u0430 \u043f\u0435\u0440\u0435\u0434 \u043a\u043d\u0438\u0436\u043d\u044b\u043c\u0438 \u043f\u043e\u043b\u043a\u0430\u043c\u0438 \u0438, \u043a\u0430\u043a \u0431\u0443\u0434\u0442\u043e, \u0441 \u043c\u0430\u0441\u043b\u044f\u043d\u043e\u0439 \u043b\u0430\u043c\u043f\u0430\u0434\u043e\u0439 (R60).<\/p>\n<div class=\"hidden_text\">La nouvelle th\u00e9matique des rencontres litt\u00e9raires de cette ann\u00e9e est \u00ab\u00a0Le livre qui a chang\u00e9 ma vie\u00a0\u00bb (C96). Christiane Taubira, Douglas Kennedy, Pierre Berg\u00e9, H\u00e9lo\u00efse d\u2019Ormesson inspireront les discussions litt\u00e9raires.<\/div>\n<div class=\"hidden_text\">De l\u2019inattendu\u00a0: le Salon du Livre de cette ann\u00e9e propose une promenade dans Paris avec l\u2019auteur Douglas Kennedy, dans un bus des ann\u00e9es 1930. Et la Fnac (magasin sp\u00e9cialis\u00e9 dans l\u2019audio et le mat\u00e9riel vid\u00e9o, ndlr) proposera de faire \u00ab\u00a0une photo d\u2019amateur de litt\u00e9rature\u00a0\u00bb. On vous conduira dans un d\u00e9barras noir et on vous photographiera avec le flash, vous n\u2019aurez pas le temps de comprendre, mais lorsque vous verrez la photographie imprim\u00e9e vous saurez que vous n\u2019\u00e9tiez pas dans un d\u00e9barras mais devant des \u00e9tag\u00e8res de livres, avec une lampe \u00e0 huile (R60).<\/div>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_18017\" style=\"width: 543px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/cult\/34-j-parizhskij-knizhnyj-salon.html\/attachment\/foto-3\" rel=\"attachment wp-att-18017\"><img aria-describedby=\"caption-attachment-18017\" loading=\"lazy\" class=\"size-large wp-image-18017\" alt=\"\" src=\"http:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-3-533x400.jpg\" width=\"533\" height=\"400\" srcset=\"https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-3-533x400.jpg 533w, https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-3.jpg 1000w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a><p id=\"caption-attachment-18017\" class=\"wp-caption-text\">\u0421\u0442\u0435\u043d\u0434 \u0438\u043d\u0441\u0442\u0438\u0442\u0443\u0442\u0430 \u041f\u0435\u0440\u0435\u0432\u043e\u0434\u0430 \u00a9Aliona Sovetova<\/p><\/div><\/p>\n<p>\u00a0\u0420\u043e\u0441\u0441\u0438\u044e \u0432 \u044d\u0442\u043e\u043c \u0433\u043e\u0434\u0443 \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442 \u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u0441\u0442\u0435\u043d\u0434 \u0420\u0426\u041d\u041a (\u0420\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u0439 \u0446\u0435\u043d\u0442\u0440 \u043d\u0430\u0443\u043a\u0438 \u0438 \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b) (S60) \u0441 \u043d\u0435\u0432\u0435\u0440\u043e\u044f\u0442\u043d\u044b\u043c\u0438 \u0445\u0443\u0434\u043e\u0436\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u043c\u0438 \u0430\u043b\u044c\u0431\u043e\u043c\u0430\u043c\u0438, \u043f\u0440\u043e\u0438\u0437\u0432\u0435\u0434\u0435\u043d\u0438\u044f\u043c\u0438 \u0440\u0443\u0441\u0441\u043a\u043e\u044f\u0437\u044b\u0447\u043d\u044b\u0445 \u0430\u0432\u0442\u043e\u0440\u043e\u0432, \u043f\u0440\u043e\u0436\u0438\u0432\u0430\u044e\u0449\u0438\u0445 \u0432\u043e \u0424\u0440\u0430\u043d\u0446\u0438\u0438 \u0438 \u0432\u044b\u0441\u0442\u0430\u0432\u043a\u043e\u0439, \u043f\u043e\u0441\u0432\u044f\u0449\u0435\u043d\u043d\u043e\u0439 \u041b\u0435\u0440\u043c\u043e\u043d\u0442\u043e\u0432\u0443, \u043d\u043e \u0438 \u0432\u043f\u0435\u0440\u0432\u044b\u0435 \u0438\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u041f\u0435\u0440\u0435\u0432\u043e\u0434\u0430 (R50) \u043f\u043e\u0434 \u0434\u0435\u0432\u0438\u0437\u043e\u043c <b>Read Russia<\/b>. \u0417\u0430\u0434\u0430\u0447\u0430 \u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442\u0430 \u2013 \u0441\u043e\u0434\u0435\u0439\u0441\u0442\u0432\u043e\u0432\u0430\u0442\u044c \u043f\u0435\u0440\u0435\u0432\u043e\u0434\u0443 \u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u0445 \u0430\u0432\u0442\u043e\u0440\u043e\u0432 \u043d\u0430 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0435 \u044f\u0437\u044b\u043a\u0438. \u0412 \u044d\u043a\u0441\u043f\u043e\u0437\u0438\u0446\u0438\u044e \u0432\u0445\u043e\u0434\u044f\u0442 \u043d\u043e\u0432\u0438\u043d\u043a\u0438 \u043e\u0442\u0435\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0433\u043e \u043a\u043d\u0438\u0436\u043d\u043e\u0433\u043e \u0440\u044b\u043d\u043a\u0430. \u0411\u043e\u043b\u044c\u0448\u043e\u0435 \u043f\u0440\u043e\u0441\u0442\u0440\u0430\u043d\u0441\u0442\u0432\u043e \u043f\u043e\u0441\u0432\u044f\u0449\u0435\u043d\u043e \u0434\u0435\u0442\u0441\u043a\u043e\u0439 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u0435. \u0412 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u043c\u0435 \u043c\u0435\u0440\u043e\u043f\u0440\u0438\u044f\u0442\u0438\u0439: \u0432\u0441\u0442\u0440\u0435\u0447\u0438 \u0441 \u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u043c\u0438 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u043e\u0440\u0430\u043c\u0438 \u0438 \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u0441\u043a\u0438\u043c\u0438 \u043f\u0435\u0440\u0435\u0432\u043e\u0434\u0447\u0438\u043a\u0430\u043c\u0438 \u043d\u0430 \u0440\u0443\u0441\u0441\u043a\u0438\u0439 \u044f\u0437\u044b\u043a, \u0441\u0435\u043c\u0438\u043d\u0430\u0440\u044b \u0434\u043b\u044f \u0444\u0440\u0430\u043d\u0446\u0443\u0437\u0441\u043a\u0438\u0445 \u0438\u0437\u0434\u0430\u0442\u0435\u043b\u0435\u0439, \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0438\u0435 \u0437\u043d\u0430\u0447\u0438\u043c\u044b\u0445 \u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u0445 \u043b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u044b\u0445 \u043f\u0440\u0435\u043c\u0438\u0439 (\u0411\u043e\u043b\u044c\u0448\u0430\u044f \u041a\u043d\u0438\u0433\u0430, \u0420\u0443\u0441\u0441\u043a\u0438\u0439 \u0411\u0443\u043a\u0435\u0440). \u0414\u043b\u044f \u0434\u0435\u0442\u0435\u0439 \u2013 \u0432\u0441\u0442\u0440\u0435\u0447\u0430 \u0441\u043e \u0441\u043a\u0430\u0437\u043e\u0447\u043d\u0438\u043a\u043e\u043c \u0421\u0435\u0440\u0433\u0435\u0435\u043c \u0421\u0435\u0434\u043e\u0432\u044b\u043c.<\/p>\n<div class=\"hidden_text\">\u00a0Cette ann\u00e9e, la Russie n\u2019a pas seulement \u00e9t\u00e9 repr\u00e9sent\u00e9e avec le stand Centre de Russie pour la Science et la Culture \u00e0 Paris (S60), avec des albums d\u2019art improbables, des \u0153uvres d\u2019auteurs russes vivant en France, et une exposition consacr\u00e9e \u00e0 Lermontov\u00a0; mais aussi pour la premi\u00e8re fois par l\u2019Institut de Traduction (R50) sous la devise <b>Read Russia<\/b>. Le but de cet Institut est d\u2019aider \u00e0 la traduction des auteurs russes dans des langues \u00e9trang\u00e8res. Les nouveaut\u00e9s du march\u00e9 national du livre se trouvaient dans l\u2019exposition. Un grand espace est consacr\u00e9 \u00e0 la litt\u00e9rature jeunesse. Au programme des animations\u00a0: des rencontres avec des hommes de lettres russes et avec des Fran\u00e7ais qui traduisent en russe, des s\u00e9minaires pour les \u00e9diteurs fran\u00e7ais et une pr\u00e9sentation des prix litt\u00e9raires russes consid\u00e9rables (le Grand Livre, le Booker russe). Pour les enfants, une rencontre avec le conteur Sergue\u00ef Sedov.<\/div>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_18018\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/cult\/34-j-parizhskij-knizhnyj-salon.html\/attachment\/foto-4\" rel=\"attachment wp-att-18018\"><img aria-describedby=\"caption-attachment-18018\" loading=\"lazy\" class=\"size-large wp-image-18018\" alt=\"\" src=\"http:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-4-300x400.jpg\" width=\"300\" height=\"400\" srcset=\"https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-4-300x400.jpg 300w, https:\/\/rusoch.fr\/files\/2014\/03\/\u0444\u043e\u0442\u043e-4.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-18018\" class=\"wp-caption-text\">\u00a9Aliona Sovetova<\/p><\/div><\/p>\n<p>\u00a0\u041d\u044b\u043d\u0435 \u0431\u044b\u0442\u0443\u0435\u0442 \u043c\u043d\u0435\u043d\u0438\u0435, \u0447\u0442\u043e \u0432 \u0441\u043e\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u043e\u043c \u043c\u0438\u0440\u0435 \u043f\u0438\u0441\u0430\u0442\u0435\u043b\u0435\u0439 \u0441\u0442\u0430\u043b\u043e \u0431\u043e\u043b\u044c\u0448\u0435, \u0447\u0435\u043c \u0447\u0438\u0442\u0430\u0442\u0435\u043b\u0435\u0439, \u0431\u0443\u043c\u0430\u0436\u043d\u0430\u044f \u043a\u043d\u0438\u0433\u0430 \u0438\u0437\u0436\u0438\u043b\u0430 \u0441\u0435\u0431\u044f, \u0430 \u0432 \u0436\u0438\u0437\u043d\u0438 \u0438\u0437\u0434\u0430\u0442\u0435\u043b\u044c\u0441\u0442\u0432 \u043d\u0430\u0441\u0442\u0443\u043f\u0438\u043b\u0430 \u0432\u0435\u0447\u043d\u0430\u044f \u043e\u0441\u0435\u043d\u044c. \u0418 \u0432\u0441\u0451 \u0436\u0435 \u0446\u0438\u0444\u0440\u0430 \u0432 198 000 \u043f\u043e\u0441\u0435\u0442\u0438\u0442\u0435\u043b\u0435\u0439 \u0421\u0430\u043b\u043e\u043d\u0430, \u0431\u0435\u0441\u043a\u043e\u043d\u0435\u0447\u043d\u043e\u0435 \u043c\u043d\u043e\u0433\u043e\u043e\u0431\u0440\u0430\u0437\u0438\u0435 \u0438 \u043b\u0438\u0447\u043d\u043e\u0435 \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u0435 \u043e\u0442 \u043d\u0435\u0436\u043d\u043e\u0439 \u0431\u043b\u0438\u0437\u043e\u0441\u0442\u0438 \u0441 \u043f\u0435\u0447\u0430\u0442\u043d\u044b\u043c \u0438\u0437\u0434\u0430\u043d\u0438\u0435\u043c \u0432\u043d\u0443\u0448\u0430\u0435\u0442 \u0441\u0442\u043e\u0439\u043a\u0438\u0439 \u043e\u043f\u0442\u0438\u043c\u0438\u0437\u043c, \u0432\u0435\u0440\u0443 \u0432 \u043a\u043d\u0438\u0436\u043d\u043e\u0435 \u0431\u0443\u0434\u0443\u0449\u0435\u0435 \u0438 \u0432\u0435\u0447\u043d\u0443\u044e \u0432\u0435\u0441\u043d\u0443.<\/p>\n<p>\u0421\u0430\u043b\u043e\u043d \u0440\u0430\u0431\u043e\u0442\u0430\u0435\u0442 \u0434\u043e 24 \u043c\u0430\u0440\u0442\u0430.<\/p>\n<div class=\"hidden_text\">Cette ann\u00e9e, la Russie n\u2019a pas seulement \u00e9t\u00e9 repr\u00e9sent\u00e9e avec le stand Centre de Russie pour la Science et la Culture \u00e0 Paris (S60), avec des albums d\u2019art improbables, des \u0153uvres d\u2019auteurs russes vivant en France, et une exposition consacr\u00e9e \u00e0 Lermontov\u00a0; mais aussi pour la premi\u00e8re fois par l\u2019Institut de Traduction (R50) sous la devise <b>Read Russia<\/b>. Le but de cet Institut est d\u2019aider \u00e0 la traduction des auteurs russes dans des langues \u00e9trang\u00e8res. Les nouveaut\u00e9s du march\u00e9 national du livre se trouvaient dans l\u2019exposition. Un grand espace est consacr\u00e9 \u00e0 la litt\u00e9rature jeunesse. Au programme des animations\u00a0: des rencontres avec des hommes de lettres russes et avec des Fran\u00e7ais qui traduisent en russe, des s\u00e9minaires pour les \u00e9diteurs fran\u00e7ais et une pr\u00e9sentation des prix litt\u00e9raires russes consid\u00e9rables (le Grand Livre, le Booker russe). Pour les enfants, une rencontre avec le conteur Sergue\u00ef Sedov.<\/div>\n<div class=\"hidden_text\">Aujourd\u2019hui, on pense que dans le monde moderne il y a plus d\u2019\u00e9crivains que de lecteurs, le livre papier meurt, et l\u2019automne \u00e9ternel est arriv\u00e9 dans la vie des maisons d\u2019\u00e9dition. Mais quand m\u00eame, les 198000 visiteurs du Salon du Livre de Paris, la diversit\u00e9 infinie et le plaisir personnel de tendre proximit\u00e9 pour l\u2019\u00e9dition imprim\u00e9e inspirent un optimisme inattaquable, une foi en l\u2019avenir du livre et en le printemps \u00e9ternel.<\/div>\n<div class=\"hidden_text\">Le Salon du Livre de Paris est ouvert jusqu\u2019au 24 mars.<\/div>\n<p>\u00a0P.S. \u0412 \u0440\u0430\u043c\u043a\u0430\u0445 \u0421\u0430\u043b\u043e\u043d\u0430 \u043d\u0430 \u0432\u0441\u0442\u0440\u0435\u0447\u0435 \u0441 \u043f\u0438\u0441\u0430\u0442\u0435\u043b\u044c\u043d\u0438\u0446\u0435\u0439, \u043f\u043e\u044d\u0442\u043e\u043c, \u0436\u0443\u0440\u043d\u0430\u043b\u0438\u0441\u0442\u043a\u043e\u0439 \u0438 \u0430\u0432\u0442\u043e\u0440\u043e\u043c <em>\u00ab\u0420\u0443\u0441\u0441\u043a\u043e\u0433\u043e \u043e\u0447\u0435\u0432\u0438\u0434\u0446\u0430\u00bb<\/em> \u041a\u0438\u0440\u043e\u0439 \u0421\u0430\u043f\u0433\u0438\u0440 22 \u043c\u0430\u0440\u0442\u0430.<\/p>\n<div class=\"hidden_text\">P.S.Lors de la rencontre avec \u00e9crivain, po\u00e8te, jouranliste et auteur de l4Observateur Russe Kira Sapguir le 22 mars 2014<\/div>\n<p>&nbsp;<\/p>\n<p><div id=\"attachment_18028\" style=\"width: 610px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/rusoch.fr\/cult\/34-j-parizhskij-knizhnyj-salon.html\/attachment\/salon-du-livre-2014-084\" rel=\"attachment wp-att-18028\"><img aria-describedby=\"caption-attachment-18028\" loading=\"lazy\" class=\" wp-image-18028\" alt=\"\" src=\"http:\/\/rusoch.fr\/files\/2014\/03\/salon-du-livre-2014-084-600x400.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/rusoch.fr\/files\/2014\/03\/salon-du-livre-2014-084-600x400.jpg 600w, https:\/\/rusoch.fr\/files\/2014\/03\/salon-du-livre-2014-084.jpg 1181w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-18028\" class=\"wp-caption-text\">\u00a9Boris Guessel<\/p><\/div><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>20 \u043c\u0430\u0440\u0442\u0430 \u0441\u043e\u0441\u0442\u043e\u044f\u043b\u043e\u0441\u044c \u0442\u043e\u0440\u0436\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0435 \u043e\u0442\u043a\u0440\u044b\u0442\u0438\u0435 34-\u0433\u043e \u043f\u0430\u0440\u0438\u0436\u0441\u043a\u043e\u0433\u043e \u041a\u043d\u0438\u0436\u043d\u043e\u0433\u043e \u0441\u0430\u043b\u043e\u043d\u0430. \u0412 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u043c\u0435 \u0432\u0435\u0447\u0435\u0440\u0430: \u0432\u0441\u0442\u0443\u043f\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0435 \u0441\u043b\u043e\u0432\u043e \u043f\u0440\u0435\u043c\u044c\u0435\u0440-\u043c\u0438\u043d\u0438\u0441\u0442\u0440\u0430 \u0424\u0440\u0430\u043d\u0446\u0438\u0438 \u0416. -\u041c. \u042d\u0440\u043e, \u0440\u0435\u0447\u044c \u043f\u0440\u0435\u0437\u0438\u0434\u0435\u043d\u0442\u0430&hellip;<\/p>\n","protected":false},"author":2,"featured_media":18028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/posts\/18008"}],"collection":[{"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/comments?post=18008"}],"version-history":[{"count":0,"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/posts\/18008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/media\/18028"}],"wp:attachment":[{"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/media?parent=18008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/categories?post=18008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rusoch.fr\/ru\/wp-json\/wp\/v2\/tags?post=18008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}